{"id":1211,"count":1,"description":"","link":"https:\/\/esoftskills.com\/healthcare\/tag\/healthcare-cybersecurity\/","name":"Healthcare Cybersecurity","slug":"healthcare-cybersecurity","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/esoftskills.com\/healthcare\/wp-json\/wp\/v2\/tags\/1211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esoftskills.com\/healthcare\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/esoftskills.com\/healthcare\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/esoftskills.com\/healthcare\/wp-json\/wp\/v2\/posts?tags=1211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}